{"id":8697,"date":"2018-12-13T14:13:15","date_gmt":"2018-12-13T13:13:15","guid":{"rendered":"http:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg"},"modified":"2018-12-13T14:13:15","modified_gmt":"2018-12-13T13:13:15","slug":"paolo_cognetti-2-2","status":"inherit","type":"attachment","link":"https:\/\/magazine.fbk.eu\/en\/paolo_cognetti-2-2\/","title":{"rendered":"Paolo_cognetti"},"author":20,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"attachment_category":[],"attachment_tag":[],"class_list":["post-8697","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paolo_cognetti - FBK MAGAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"FBK MAGAZINE\" \/>\n<meta property=\"og:image\" content=\"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"544\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/magazine.fbk.eu\/wp-content\/themes\/fbk-magazine\/images\/opengraph-default.png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magazine.fbk.eu\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Paolo_cognetti-1.jpg\",\"url\":\"https:\\\/\\\/magazine.fbk.eu\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Paolo_cognetti-1.jpg\",\"name\":\"Paolo_cognetti - FBK MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magazine.fbk.eu\\\/en\\\/#website\"},\"datePublished\":\"2018-12-13T13:13:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magazine.fbk.eu\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Paolo_cognetti-1.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magazine.fbk.eu\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Paolo_cognetti-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magazine.fbk.eu\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Paolo_cognetti-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/magazine.fbk.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paolo_cognetti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magazine.fbk.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/magazine.fbk.eu\\\/en\\\/\",\"name\":\"FBK MAGAZINE\",\"description\":\"Fondazione Bruno Kessler\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magazine.fbk.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paolo_cognetti - FBK MAGAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg","og_locale":"en_US","og_type":"article","og_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg","og_site_name":"FBK MAGAZINE","og_image":[{"width":544,"height":532,"url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/magazine.fbk.eu\/wp-content\/themes\/fbk-magazine\/images\/opengraph-default.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg","url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg","name":"Paolo_cognetti - FBK MAGAZINE","isPartOf":{"@id":"https:\/\/magazine.fbk.eu\/en\/#website"},"datePublished":"2018-12-13T13:13:15+00:00","breadcrumb":{"@id":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/magazine.fbk.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Paolo_cognetti"}]},{"@type":"WebSite","@id":"https:\/\/magazine.fbk.eu\/en\/#website","url":"https:\/\/magazine.fbk.eu\/en\/","name":"FBK MAGAZINE","description":"Fondazione Bruno Kessler","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magazine.fbk.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"meta_box":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-300x300.jpg 300w, https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-150x150.jpg 150w, https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-1024x1024.jpg 1024w, https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-96x96.jpg 96w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":544,"height":532,"file":"2018\/12\/Paolo_cognetti-1.jpg","sizes":{"thumbnail":{"file":"Paolo_cognetti-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-150x150.jpg"},"medium":{"file":"Paolo_cognetti-1-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-300x300.jpg"},"large":{"file":"Paolo_cognetti-1-1024x1024.jpg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-1024x1024.jpg"},"magazine-slider":{"file":"Paolo_cognetti-1-1600x880.jpg","width":1600,"height":880,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-1600x880.jpg"},"magazine-full":{"file":"Paolo_cognetti-1-1600x700.jpg","width":1600,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-1600x700.jpg"},"magazine-big":{"file":"Paolo_cognetti-1-1060x600.jpg","width":1060,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-1060x600.jpg"},"magazine-medium":{"file":"Paolo_cognetti-1-530x600.jpg","width":530,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-530x600.jpg"},"magazine-small":{"file":"Paolo_cognetti-1-480x350.jpg","width":480,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-480x350.jpg"},"piklist_file_preview":{"file":"Paolo_cognetti-1-96x96.jpg","width":96,"height":96,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1-96x96.jpg"},"full":{"file":"Paolo_cognetti-1.jpg","width":544,"height":532,"mime_type":"image\/jpeg","source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1544709329","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/magazine.fbk.eu\/wp-content\/uploads\/2018\/12\/Paolo_cognetti-1.jpg","_links":{"self":[{"href":"https:\/\/magazine.fbk.eu\/en\/wp-json\/wp\/v2\/media\/8697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazine.fbk.eu\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/magazine.fbk.eu\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/magazine.fbk.eu\/en\/wp-json\/wp\/v2\/users\/20"}],"wp:term":[{"taxonomy":"attachment_category","embeddable":true,"href":"https:\/\/magazine.fbk.eu\/en\/wp-json\/wp\/v2\/attachment_category?post=8697"},{"taxonomy":"attachment_tag","embeddable":true,"href":"https:\/\/magazine.fbk.eu\/en\/wp-json\/wp\/v2\/attachment_tag?post=8697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}